{"id":4628,"date":"2024-08-29T12:19:22","date_gmt":"2024-08-29T10:19:22","guid":{"rendered":"https:\/\/www.loni-infos.com\/?p=4628"},"modified":"2024-08-29T12:19:25","modified_gmt":"2024-08-29T10:19:25","slug":"les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales","status":"publish","type":"post","link":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/","title":{"rendered":"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales"},"content":{"rendered":"\n<p>Le forum des forces sociales de Guin\u00e9e \u00e9tait face \u00e0 la presse ce mercredi 28 ao\u00fbt 2024. Une conf\u00e9rence de presse consacr\u00e9e sur la disparition de Fonik\u00e9 Menguet et de Billo Bah. Au cours de cette conf\u00e9rence de presse, Ibrahima Aminata Diallo a r\u00e9v\u00e9l\u00e9 que \u00ab <em>le domicile de Fonik\u00e9 Menguet est ferm\u00e9, carr\u00e9ment ferm\u00e9. Mais il y a des individus qui viennent autour de son domicile, parce qu\u2019ils auraient appris, je le mets au conditionnel, qu\u2019il y a une cam\u00e9ra cach\u00e9e. Donc ils veulent co\u00fbte que co\u00fbte, retirer cette cam\u00e9ra cach\u00e9e pour effacer les traces de la pr\u00e9sence de ceux qui sont venus l\u2019arr\u00eater. Il faudra qu\u2019on soit claire avec vous. Aujourd\u2019hui sa famille, personne n\u2019est l\u00e0-bas<\/em> \u00bb.<\/p>\n\n\n\n<p>Ibrahima Aminata Diallo a rappel\u00e9 que les familles des deux activistes sont traumatis\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le forum des forces sociales de Guin\u00e9e \u00e9tait face \u00e0 la presse ce mercredi 28 ao\u00fbt 2024. Une conf\u00e9rence de presse consacr\u00e9e sur la disparition de Fonik\u00e9 Menguet et de Billo Bah. Au cours de cette conf\u00e9rence de presse, Ibrahima Aminata Diallo a r\u00e9v\u00e9l\u00e9 que \u00ab le domicile de Fonik\u00e9 Menguet est ferm\u00e9, carr\u00e9ment ferm\u00e9.<\/p>\n","protected":false},"author":1,"featured_media":4629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[96,17,101],"class_list":{"0":"post-4628","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-societe","8":"tag-cellou-dalein-diallo","9":"tag-guinee","10":"tag-ufdg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales - Loni-infos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales - Loni-infos\" \/>\n<meta property=\"og:description\" content=\"Le forum des forces sociales de Guin\u00e9e \u00e9tait face \u00e0 la presse ce mercredi 28 ao\u00fbt 2024. Une conf\u00e9rence de presse consacr\u00e9e sur la disparition de Fonik\u00e9 Menguet et de Billo Bah. Au cours de cette conf\u00e9rence de presse, Ibrahima Aminata Diallo a r\u00e9v\u00e9l\u00e9 que \u00ab le domicile de Fonik\u00e9 Menguet est ferm\u00e9, carr\u00e9ment ferm\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/\" \/>\n<meta property=\"og:site_name\" content=\"Loni-infos\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T10:19:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T10:19:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales\",\"datePublished\":\"2024-08-29T10:19:22+00:00\",\"dateModified\":\"2024-08-29T10:19:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/\"},\"wordCount\":167,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg\",\"keywords\":[\"Cellou Dalein Diallo\",\"Guin\u00e9e\",\"UFDG\"],\"articleSection\":[\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/\",\"name\":\"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales - Loni-infos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg\",\"datePublished\":\"2024-08-29T10:19:22+00:00\",\"dateModified\":\"2024-08-29T10:19:25+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg\",\"width\":1008,\"height\":567},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/08\\\/29\\\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.loni-infos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/#website\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/\",\"name\":\"Loni-infos\",\"description\":\"Vous servir des infos est notre devoir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.loni-infos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales - Loni-infos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales - Loni-infos","og_description":"Le forum des forces sociales de Guin\u00e9e \u00e9tait face \u00e0 la presse ce mercredi 28 ao\u00fbt 2024. Une conf\u00e9rence de presse consacr\u00e9e sur la disparition de Fonik\u00e9 Menguet et de Billo Bah. Au cours de cette conf\u00e9rence de presse, Ibrahima Aminata Diallo a r\u00e9v\u00e9l\u00e9 que \u00ab le domicile de Fonik\u00e9 Menguet est ferm\u00e9, carr\u00e9ment ferm\u00e9.","og_url":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/","og_site_name":"Loni-infos","article_published_time":"2024-08-29T10:19:22+00:00","article_modified_time":"2024-08-29T10:19:25+00:00","og_image":[{"width":1008,"height":567,"url":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#article","isPartOf":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/"},"author":{"name":"","@id":""},"headline":"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales","datePublished":"2024-08-29T10:19:22+00:00","dateModified":"2024-08-29T10:19:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/"},"wordCount":167,"commentCount":0,"image":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg","keywords":["Cellou Dalein Diallo","Guin\u00e9e","UFDG"],"articleSection":["Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/","url":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/","name":"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales - Loni-infos","isPartOf":{"@id":"https:\/\/www.loni-infos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#primaryimage"},"image":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg","datePublished":"2024-08-29T10:19:22+00:00","dateModified":"2024-08-29T10:19:25+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#primaryimage","url":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg","contentUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-19.01.40.jpeg","width":1008,"height":567},{"@type":"BreadcrumbList","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/08\/29\/les-familles-des-deux-activistes-sont-traumatisees-revele-un-acteur-des-forces-sociales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.loni-infos.com\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Les familles des deux activistes sont traumatis\u00e9es\u00a0\u00bb r\u00e9v\u00e9l\u00e9 un acteur des forces sociales"}]},{"@type":"WebSite","@id":"https:\/\/www.loni-infos.com\/#website","url":"https:\/\/www.loni-infos.com\/","name":"Loni-infos","description":"Vous servir des infos est notre devoir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.loni-infos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"","url":"https:\/\/www.loni-infos.com\/index.php\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/4628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/comments?post=4628"}],"version-history":[{"count":1,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/4628\/revisions"}],"predecessor-version":[{"id":4630,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/4628\/revisions\/4630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/media\/4629"}],"wp:attachment":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/media?parent=4628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/categories?post=4628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/tags?post=4628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}