{"id":4733,"date":"2024-09-11T14:47:53","date_gmt":"2024-09-11T12:47:53","guid":{"rendered":"https:\/\/www.loni-infos.com\/?p=4733"},"modified":"2024-09-11T14:47:57","modified_gmt":"2024-09-11T12:47:57","slug":"cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres","status":"publish","type":"post","link":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/","title":{"rendered":"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres"},"content":{"rendered":"\n<p>Le conseil interminist\u00e9riel s\u2019est tenu ce mardi \u00e0 la primature sous la pr\u00e9sidence du chef du Gouvernement. Un conseil marqu\u00e9 par l\u2019intervention du premier concernant les inondations que la Guin\u00e9e a enregistr\u00e9 les semaines derni\u00e8res. Sur cette question, Bah Oury a port\u00e9 \u00e0 la connaissance des ministres qu\u2019\u00e0 date, la somme de 10 milliards de francs guin\u00e9ens a \u00e9t\u00e9 mobilis\u00e9e pour porter assistance aux sinistr\u00e9s des inondations. \u00ab <em>Le message du Premier ministre a port\u00e9 sur les catastrophes provoqu\u00e9es par des inondations que notre pays a connues depuis deux semaines. Il a f\u00e9licit\u00e9 tous les ministres qui se sont engag\u00e9s au secours des populations sinistr\u00e9es. Il a rappel\u00e9 toutes les mesures d\u2019urgence et a inform\u00e9 le Conseil de la mobilisation d\u2019une somme de 10 milliards de francs guin\u00e9ens pour faire face aux besoins urgents des populations sinistr\u00e9es et a appel\u00e9 la population \u00e0 la solidarit\u00e9 nationale pour aider nos concitoyens qui sont victimes d\u2019inondations et autres catastrophes depuis deux semaines<\/em> \u00bb affirme Ousmane Gaoual Diallo, porte-parole du gouvernement<\/p>\n\n\n\n<p>L\u2019autre question \u00e9voqu\u00e9e par le locataire du palais de la Colombe portait sur les dispositions contre les attaques arm\u00e9es \u00e0 domicile et les tueries pendant des manifestations citoyennes. Sur cette question, le porte-parole du gouvernement, Ousmane Gaoual Diallo rapporte ceci : \u00ab <em>Il<\/em> (Bah Oury) <em>a rappel\u00e9 aux ministres en charge de la S\u00e9curit\u00e9, de la Justice, de l\u2019Administration du territoire, de la D\u00e9fense, d\u2019intensifier leurs activit\u00e9s pour mieux s\u00e9curiser nos populations. Il a d\u00e9plor\u00e9 les attaques \u00e0 domicile qui ont endeuill\u00e9 certaines familles guin\u00e9ennes. Il a rappel\u00e9 \u00e0 cette occasion qu\u2019il n\u2019\u00e9tait pas normal que des Guin\u00e9ens continuent de tomber \u00e0 l\u2019occasion des manifestations de rue. Il a invit\u00e9 le minist\u00e8re de la Justice \u00e0 s\u2019auto-saisir syst\u00e9matiquement lorsqu\u2019il y a des cas de d\u00e9c\u00e8s enregistr\u00e9s \u00e0 l\u2019occasion de ces manifestations. Il a rappel\u00e9 que les r\u00e8gles du maintien d\u2019ordre doivent \u00eatre respect\u00e9es scrupuleusement et a invit\u00e9 les ministres de la D\u00e9fense et de la s\u00e9curit\u00e9 de veiller \u00e0 cela \u00e0 l\u2019occasion des manifestations pour que les Guin\u00e9ens cessent de compter des victimes lors des manifestation de rue <\/em>\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le conseil interminist\u00e9riel s\u2019est tenu ce mardi \u00e0 la primature sous la pr\u00e9sidence du chef du Gouvernement. Un conseil marqu\u00e9 par l\u2019intervention du premier concernant les inondations que la Guin\u00e9e a enregistr\u00e9 les semaines derni\u00e8res. Sur cette question, Bah Oury a port\u00e9 \u00e0 la connaissance des ministres qu\u2019\u00e0 date, la somme de 10 milliards de<\/p>\n","protected":false},"author":1,"featured_media":4600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[162,96,101],"class_list":{"0":"post-4733","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-societe","8":"tag-bah-oury","9":"tag-cellou-dalein-diallo","10":"tag-ufdg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres - Loni-infos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres - Loni-infos\" \/>\n<meta property=\"og:description\" content=\"Le conseil interminist\u00e9riel s\u2019est tenu ce mardi \u00e0 la primature sous la pr\u00e9sidence du chef du Gouvernement. Un conseil marqu\u00e9 par l\u2019intervention du premier concernant les inondations que la Guin\u00e9e a enregistr\u00e9 les semaines derni\u00e8res. Sur cette question, Bah Oury a port\u00e9 \u00e0 la connaissance des ministres qu\u2019\u00e0 date, la somme de 10 milliards de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/\" \/>\n<meta property=\"og:site_name\" content=\"Loni-infos\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-11T12:47:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T12:47:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/Bah-Oury.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres\",\"datePublished\":\"2024-09-11T12:47:53+00:00\",\"dateModified\":\"2024-09-11T12:47:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/\"},\"wordCount\":390,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Bah-Oury.jpg\",\"keywords\":[\"Bah Oury\",\"Cellou Dalein Diallo\",\"UFDG\"],\"articleSection\":[\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/\",\"name\":\"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres - Loni-infos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Bah-Oury.jpg\",\"datePublished\":\"2024-09-11T12:47:53+00:00\",\"dateModified\":\"2024-09-11T12:47:57+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Bah-Oury.jpg\",\"contentUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Bah-Oury.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/09\\\/11\\\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.loni-infos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/#website\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/\",\"name\":\"Loni-infos\",\"description\":\"Vous servir des infos est notre devoir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.loni-infos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres - Loni-infos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/","og_locale":"fr_FR","og_type":"article","og_title":"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres - Loni-infos","og_description":"Le conseil interminist\u00e9riel s\u2019est tenu ce mardi \u00e0 la primature sous la pr\u00e9sidence du chef du Gouvernement. Un conseil marqu\u00e9 par l\u2019intervention du premier concernant les inondations que la Guin\u00e9e a enregistr\u00e9 les semaines derni\u00e8res. Sur cette question, Bah Oury a port\u00e9 \u00e0 la connaissance des ministres qu\u2019\u00e0 date, la somme de 10 milliards de","og_url":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/","og_site_name":"Loni-infos","article_published_time":"2024-09-11T12:47:53+00:00","article_modified_time":"2024-09-11T12:47:57+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/Bah-Oury.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#article","isPartOf":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/"},"author":{"name":"","@id":""},"headline":"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres","datePublished":"2024-09-11T12:47:53+00:00","dateModified":"2024-09-11T12:47:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/"},"wordCount":390,"commentCount":0,"image":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/Bah-Oury.jpg","keywords":["Bah Oury","Cellou Dalein Diallo","UFDG"],"articleSection":["Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/","url":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/","name":"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres - Loni-infos","isPartOf":{"@id":"https:\/\/www.loni-infos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#primaryimage"},"image":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/Bah-Oury.jpg","datePublished":"2024-09-11T12:47:53+00:00","dateModified":"2024-09-11T12:47:57+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#primaryimage","url":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/Bah-Oury.jpg","contentUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/08\/Bah-Oury.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/09\/11\/cas-de-morts-lors-des-manifestations-bah-oury-donne-des-instructions-aux-ministres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.loni-infos.com\/"},{"@type":"ListItem","position":2,"name":"Cas de morts lors des manifestations : Bah Oury donne des instructions aux ministres"}]},{"@type":"WebSite","@id":"https:\/\/www.loni-infos.com\/#website","url":"https:\/\/www.loni-infos.com\/","name":"Loni-infos","description":"Vous servir des infos est notre devoir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.loni-infos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"","url":"https:\/\/www.loni-infos.com\/index.php\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/4733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/comments?post=4733"}],"version-history":[{"count":1,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/4733\/revisions"}],"predecessor-version":[{"id":4734,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/4733\/revisions\/4734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/media\/4600"}],"wp:attachment":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/media?parent=4733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/categories?post=4733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/tags?post=4733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}