{"id":5226,"date":"2024-11-20T13:54:59","date_gmt":"2024-11-20T12:54:59","guid":{"rendered":"https:\/\/www.loni-infos.com\/?p=5226"},"modified":"2024-11-20T13:55:44","modified_gmt":"2024-11-20T12:55:44","slug":"congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays","status":"publish","type":"post","link":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/","title":{"rendered":"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#8217;int\u00e9rieur du pays."},"content":{"rendered":"\n<p>L\u2019union des forces d\u00e9mocratiques de Guin\u00e9e continue la mise en place de ses f\u00e9d\u00e9rations \u00e0 l\u2019int\u00e9rieur du pays. Apr\u00e8s Mandiana, la mission de la d\u00e9l\u00e9gation du bureau national compos\u00e9e entre autres de Cellou Balde et de Souleymane Souza Konat\u00e9 a proc\u00e9d\u00e9 \u00e0 l\u2019\u00e9lection du bureau f\u00e9d\u00e9ral de l\u2019UFDG \u00e0 Kankan. Jusque-l\u00e0 f\u00e9d\u00e9ral du parti UFDG a Kankan, Antoine Dogbo Guilavogui a \u00e9t\u00e9 reconduit dans ces fonctions du responsable f\u00e9d\u00e9ral pour 4 ans \u00e0 l\u2019issue d\u2019un vote.<\/p>\n\n\n\n<p>La m\u00eame d\u00e9l\u00e9gation poursuit sa tourn\u00e9e dans la r\u00e9gion de la haute Guin\u00e9e pour l\u2019installation des f\u00e9d\u00e9rations de Dabola, Kouroussa, Dinguiraye et Siguiri. \u00ab <em>Respectueux des textes<\/em> \u00bb notamment du statut et r\u00e8glement int\u00e9rieur du parti et de la charte des partis politiques en R\u00e9publique de Guin\u00e9e, le parti de Cellou Dalein Diallo \u00ab <em>n\u2019a pas attendu les injonctions du MATD \u00bb pour commencer \u00e0 renouveler ses bureaux. Souleymane Souza Konat\u00e9 pr\u00e9cise que \u00ab l\u2019\u00e9tape de la moyenne Guin\u00e9e est quasiment termin\u00e9e. Dans la zone de Kindia, c\u2019est quasiment boucl\u00e9. A Conakry et dans la zone de Bok\u00e9, il y a une mission qui est en train de travailler. Et nous, nous sommes du c\u00f4t\u00e9 de la haute Guin\u00e9e. Il y a une mission qui va quitter le vendredi prochain pour aller dans la zone foresti\u00e8re. Nous esp\u00e9rons finir tout \u00e7a avant le 10 d\u00e9cembre. Nous allons programmer notre congr\u00e8s national \u00e0 Conakry qui va \u00eatre pr\u00e9sident par son excellence Elhadji Cellou Dalein Diallo <\/em>\u00bb d\u00e9clare le Conseiller Charg\u00e9 de Communication de Cellou Dalein Diallo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019union des forces d\u00e9mocratiques de Guin\u00e9e continue la mise en place de ses f\u00e9d\u00e9rations \u00e0 l\u2019int\u00e9rieur du pays. Apr\u00e8s Mandiana, la mission de la d\u00e9l\u00e9gation du bureau national compos\u00e9e entre autres de Cellou Balde et de Souleymane Souza Konat\u00e9 a proc\u00e9d\u00e9 \u00e0 l\u2019\u00e9lection du bureau f\u00e9d\u00e9ral de l\u2019UFDG \u00e0 Kankan. Jusque-l\u00e0 f\u00e9d\u00e9ral du parti UFDG<\/p>\n","protected":false},"author":1,"featured_media":5227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[96,295,101],"class_list":{"0":"post-5226","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politique","8":"tag-cellou-dalein-diallo","9":"tag-kankan","10":"tag-ufdg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#039;int\u00e9rieur du pays. - Loni-infos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#039;int\u00e9rieur du pays. - Loni-infos\" \/>\n<meta property=\"og:description\" content=\"L\u2019union des forces d\u00e9mocratiques de Guin\u00e9e continue la mise en place de ses f\u00e9d\u00e9rations \u00e0 l\u2019int\u00e9rieur du pays. Apr\u00e8s Mandiana, la mission de la d\u00e9l\u00e9gation du bureau national compos\u00e9e entre autres de Cellou Balde et de Souleymane Souza Konat\u00e9 a proc\u00e9d\u00e9 \u00e0 l\u2019\u00e9lection du bureau f\u00e9d\u00e9ral de l\u2019UFDG \u00e0 Kankan. Jusque-l\u00e0 f\u00e9d\u00e9ral du parti UFDG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/\" \/>\n<meta property=\"og:site_name\" content=\"Loni-infos\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T12:54:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T12:55:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#8217;int\u00e9rieur du pays.\",\"datePublished\":\"2024-11-20T12:54:59+00:00\",\"dateModified\":\"2024-11-20T12:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/\"},\"wordCount\":304,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg\",\"keywords\":[\"Cellou Dalein Diallo\",\"Kankan\",\"UFDG\"],\"articleSection\":[\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/\",\"name\":\"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l'int\u00e9rieur du pays. - Loni-infos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg\",\"datePublished\":\"2024-11-20T12:54:59+00:00\",\"dateModified\":\"2024-11-20T12:55:44+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.loni-infos.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg\",\"width\":1080,\"height\":720,\"caption\":\"sur la photo; Mai kadidja, Cellou Balde et Souleymane Souza Konate\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/2024\\\/11\\\/20\\\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.loni-infos.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#8217;int\u00e9rieur du pays.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.loni-infos.com\\\/#website\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/\",\"name\":\"Loni-infos\",\"description\":\"Vous servir des infos est notre devoir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.loni-infos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.loni-infos.com\\\/index.php\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l'int\u00e9rieur du pays. - Loni-infos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/","og_locale":"fr_FR","og_type":"article","og_title":"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l'int\u00e9rieur du pays. - Loni-infos","og_description":"L\u2019union des forces d\u00e9mocratiques de Guin\u00e9e continue la mise en place de ses f\u00e9d\u00e9rations \u00e0 l\u2019int\u00e9rieur du pays. Apr\u00e8s Mandiana, la mission de la d\u00e9l\u00e9gation du bureau national compos\u00e9e entre autres de Cellou Balde et de Souleymane Souza Konat\u00e9 a proc\u00e9d\u00e9 \u00e0 l\u2019\u00e9lection du bureau f\u00e9d\u00e9ral de l\u2019UFDG \u00e0 Kankan. Jusque-l\u00e0 f\u00e9d\u00e9ral du parti UFDG","og_url":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/","og_site_name":"Loni-infos","article_published_time":"2024-11-20T12:54:59+00:00","article_modified_time":"2024-11-20T12:55:44+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#article","isPartOf":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/"},"author":{"name":"","@id":""},"headline":"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#8217;int\u00e9rieur du pays.","datePublished":"2024-11-20T12:54:59+00:00","dateModified":"2024-11-20T12:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/"},"wordCount":304,"commentCount":0,"image":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg","keywords":["Cellou Dalein Diallo","Kankan","UFDG"],"articleSection":["Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/","url":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/","name":"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l'int\u00e9rieur du pays. - Loni-infos","isPartOf":{"@id":"https:\/\/www.loni-infos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#primaryimage"},"image":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg","datePublished":"2024-11-20T12:54:59+00:00","dateModified":"2024-11-20T12:55:44+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#primaryimage","url":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg","contentUrl":"https:\/\/www.loni-infos.com\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-18-at-00.23.50.jpeg","width":1080,"height":720,"caption":"sur la photo; Mai kadidja, Cellou Balde et Souleymane Souza Konate"},{"@type":"BreadcrumbList","@id":"https:\/\/www.loni-infos.com\/index.php\/2024\/11\/20\/congres-de-lufdg-le-parti-accelere-ses-activites-a-linterieur-du-pays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.loni-infos.com\/"},{"@type":"ListItem","position":2,"name":"Congr\u00e8s de l\u2019UFDG : le parti acc\u00e9l\u00e8re ses activit\u00e9s \u00e0 l&#8217;int\u00e9rieur du pays."}]},{"@type":"WebSite","@id":"https:\/\/www.loni-infos.com\/#website","url":"https:\/\/www.loni-infos.com\/","name":"Loni-infos","description":"Vous servir des infos est notre devoir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.loni-infos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"","url":"https:\/\/www.loni-infos.com\/index.php\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/5226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/comments?post=5226"}],"version-history":[{"count":1,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/5226\/revisions"}],"predecessor-version":[{"id":5228,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/posts\/5226\/revisions\/5228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/media\/5227"}],"wp:attachment":[{"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/media?parent=5226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/categories?post=5226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.loni-infos.com\/index.php\/wp-json\/wp\/v2\/tags?post=5226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}